{"id":2372,"date":"2025-05-14T21:53:05","date_gmt":"2025-05-14T19:53:05","guid":{"rendered":"https:\/\/cruisearoya.com\/cruises\/istanbul-to-greece\/"},"modified":"2026-03-20T10:17:40","modified_gmt":"2026-03-20T09:17:40","slug":"istanbul-to-greece","status":"publish","type":"cruise","link":"https:\/\/cruisearoya.com\/it\/cruises\/istanbul-to-greece\/","title":{"rendered":"Vivi la magia della Turchia e della Grecia con una crociera AROYA di 7 notti da Istanbul 2026"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Vivi la magia della Turchia e della Grecia con una crociera AROYA di 7 notti da Istanbul<br><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Salpa da Istanbul, la citt\u00e0 pi\u00f9 grande della Turchia e un vivace crocevia di cultura, storia e vita moderna. Goditi una rilassante giornata in mare mentre crei momenti indimenticabili a bordo di AROYA Cruises, circondato da servizi di livello mondiale e intrattenimento di prima classe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il tuo viaggio prosegue verso l\u2019affascinante citt\u00e0 costiera di Bodrum, dove la cultura senza tempo si fonde armoniosamente con lo stile contemporaneo. Da l\u00ec, scopri Rodi, un\u2019isola patrimonio mondiale dell\u2019UNESCO, celebre per la sua ricca storia, l\u2019architettura medievale e le spiagge mozzafiato.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Successivamente, arrivi a Mykonos, la scintillante perla delle Cicladi, famosa per i suoi paesaggi spettacolari e la sua atmosfera vivace. Prosegui verso il Pireo, porta d\u2019accesso ad Atene, dove puoi gustare deliziosi piatti di pesce fresco ed esplorare alcuni dei monumenti storici pi\u00f9 iconici al mondo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dopo un\u2019altra rigenerante giornata in mare, ricca di esperienze straordinarie a bordo, il tuo viaggio indimenticabile si conclude tornando a Istanbul.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Partenze disponibili tra giugno e settembre 2026<br><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prezzi a partire da<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><tbody><tr><td>Interna<\/td><td>\u20ac 741<\/td><\/tr><tr><td>Esterma<\/td><td>\u20ac 957<\/td><\/tr><tr><td>Balcone<\/td><td>\u20ac 1244<\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Vivi la magia della Turchia e della Grecia con una crociera AROYA di 7 notti da Istanbul Salpa da Istanbul, la citt\u00e0 pi\u00f9 grande della Turchia e un vivace crocevia di cultura, storia e vita moderna. Goditi una rilassante giornata in mare mentre crei momenti indimenticabili a bordo di AROYA Cruises, circondato da servizi di<\/p>\n","protected":false},"author":1,"featured_media":30558,"parent":0,"menu_order":2,"comment_status":"closed","ping_status":"open","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2372","cruise","type-cruise","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/cruisearoya.com\/it\/wp-json\/wp\/v2\/cruise\/2372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cruisearoya.com\/it\/wp-json\/wp\/v2\/cruise"}],"about":[{"href":"https:\/\/cruisearoya.com\/it\/wp-json\/wp\/v2\/types\/cruise"}],"author":[{"embeddable":true,"href":"https:\/\/cruisearoya.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/cruisearoya.com\/it\/wp-json\/wp\/v2\/comments?post=2372"}],"version-history":[{"count":24,"href":"https:\/\/cruisearoya.com\/it\/wp-json\/wp\/v2\/cruise\/2372\/revisions"}],"predecessor-version":[{"id":31000,"href":"https:\/\/cruisearoya.com\/it\/wp-json\/wp\/v2\/cruise\/2372\/revisions\/31000"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cruisearoya.com\/it\/wp-json\/wp\/v2\/media\/30558"}],"wp:attachment":[{"href":"https:\/\/cruisearoya.com\/it\/wp-json\/wp\/v2\/media?parent=2372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}